{"id":6082,"date":"2023-02-13T18:46:36","date_gmt":"2023-02-13T18:46:36","guid":{"rendered":"https:\/\/test.ornellaprosperi.com\/?post_type=product&#038;p=6082"},"modified":"2026-02-09T13:01:52","modified_gmt":"2026-02-09T13:01:52","slug":"pantalone-poliestere-traspirante","status":"publish","type":"product","link":"https:\/\/ornellaprosperi.com\/en\/product\/pantalone-poliestere-traspirante\/","title":{"rendered":"Breathable polyester breeches"},"content":{"rendered":"<p>Standard polyester breeches made of breathable and durable fabric. Stretchy lycra bottom.<\/p>\n<p>Printed or embroidered names or logos on the legs and on the back.<\/p>\n<p>Made in Italy.<\/p>","protected":false},"excerpt":{"rendered":"<p>Standard polyester breeches made of breathable and durable fabric. Stretchy lycra bottom.<\/p>","protected":false},"featured_media":8571,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[24,31,143],"product_tag":[],"class_list":["post-6082","product","type-product","status-publish","has-post-thumbnail","product_cat-abbigliamento","product_cat-all-galoppo","product_cat-pantaloni-galoppo","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pantalone poliestere traspirante - Ornella Prosperi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ornellaprosperi.com\/en\/product\/pantalone-poliestere-traspirante\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pantalone poliestere traspirante - Ornella Prosperi\" \/>\n<meta property=\"og:description\" content=\"Pantalone da corsa in poliestere traspirante, resistente e idrorepellente con gambale in lycra.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ornellaprosperi.com\/en\/product\/pantalone-poliestere-traspirante\/\" \/>\n<meta property=\"og:site_name\" content=\"Ornella Prosperi\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T13:01:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ornellaprosperi.com\/wp-content\/uploads\/2023\/02\/pantalone-traspirante-021-fronte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ornellaprosperi.com\\\/product\\\/pantalone-poliestere-traspirante\\\/\",\"url\":\"https:\\\/\\\/ornellaprosperi.com\\\/product\\\/pantalone-poliestere-traspirante\\\/\",\"name\":\"Pantalone poliestere traspirante - Ornella Prosperi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ornellaprosperi.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ornellaprosperi.com\\\/product\\\/pantalone-poliestere-traspirante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ornellaprosperi.com\\\/product\\\/pantalone-poliestere-traspirante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ornellaprosperi.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/pantalone-traspirante-021-fronte.jpg\",\"datePublished\":\"2023-02-13T18:46:36+00:00\",\"dateModified\":\"2026-02-09T13:01:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ornellaprosperi.com\\\/product\\\/pantalone-poliestere-traspirante\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ornellaprosperi.com\\\/product\\\/pantalone-poliestere-traspirante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ornellaprosperi.com\\\/product\\\/pantalone-poliestere-traspirante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ornellaprosperi.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/pantalone-traspirante-021-fronte.jpg\",\"contentUrl\":\"https:\\\/\\\/ornellaprosperi.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/pantalone-traspirante-021-fronte.jpg\",\"width\":1000,\"height\":1300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ornellaprosperi.com\\\/product\\\/pantalone-poliestere-traspirante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ornellaprosperi.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/ornellaprosperi.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pantalone poliestere traspirante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ornellaprosperi.com\\\/#website\",\"url\":\"https:\\\/\\\/ornellaprosperi.com\\\/\",\"name\":\"Ornella Prosperi\",\"description\":\"Abbigliamento e accessori da corsa per fantini\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ornellaprosperi.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pantalone poliestere traspirante - Ornella Prosperi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ornellaprosperi.com\/en\/product\/pantalone-poliestere-traspirante\/","og_locale":"en_GB","og_type":"article","og_title":"Pantalone poliestere traspirante - Ornella Prosperi","og_description":"Pantalone da corsa in poliestere traspirante, resistente e idrorepellente con gambale in lycra.","og_url":"https:\/\/ornellaprosperi.com\/en\/product\/pantalone-poliestere-traspirante\/","og_site_name":"Ornella Prosperi","article_modified_time":"2026-02-09T13:01:52+00:00","og_image":[{"width":1000,"height":1300,"url":"https:\/\/ornellaprosperi.com\/wp-content\/uploads\/2023\/02\/pantalone-traspirante-021-fronte.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ornellaprosperi.com\/product\/pantalone-poliestere-traspirante\/","url":"https:\/\/ornellaprosperi.com\/product\/pantalone-poliestere-traspirante\/","name":"Pantalone poliestere traspirante - Ornella Prosperi","isPartOf":{"@id":"https:\/\/ornellaprosperi.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ornellaprosperi.com\/product\/pantalone-poliestere-traspirante\/#primaryimage"},"image":{"@id":"https:\/\/ornellaprosperi.com\/product\/pantalone-poliestere-traspirante\/#primaryimage"},"thumbnailUrl":"https:\/\/ornellaprosperi.com\/wp-content\/uploads\/2023\/02\/pantalone-traspirante-021-fronte.jpg","datePublished":"2023-02-13T18:46:36+00:00","dateModified":"2026-02-09T13:01:52+00:00","breadcrumb":{"@id":"https:\/\/ornellaprosperi.com\/product\/pantalone-poliestere-traspirante\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ornellaprosperi.com\/product\/pantalone-poliestere-traspirante\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ornellaprosperi.com\/product\/pantalone-poliestere-traspirante\/#primaryimage","url":"https:\/\/ornellaprosperi.com\/wp-content\/uploads\/2023\/02\/pantalone-traspirante-021-fronte.jpg","contentUrl":"https:\/\/ornellaprosperi.com\/wp-content\/uploads\/2023\/02\/pantalone-traspirante-021-fronte.jpg","width":1000,"height":1300},{"@type":"BreadcrumbList","@id":"https:\/\/ornellaprosperi.com\/product\/pantalone-poliestere-traspirante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ornellaprosperi.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/ornellaprosperi.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Pantalone poliestere traspirante"}]},{"@type":"WebSite","@id":"https:\/\/ornellaprosperi.com\/#website","url":"https:\/\/ornellaprosperi.com\/","name":"Ornella Prosperi","description":"Abbigliamento e accessori da corsa per fantini","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ornellaprosperi.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/ornellaprosperi.com\/en\/wp-json\/wp\/v2\/product\/6082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ornellaprosperi.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ornellaprosperi.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ornellaprosperi.com\/en\/wp-json\/wp\/v2\/comments?post=6082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ornellaprosperi.com\/en\/wp-json\/wp\/v2\/media\/8571"}],"wp:attachment":[{"href":"https:\/\/ornellaprosperi.com\/en\/wp-json\/wp\/v2\/media?parent=6082"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ornellaprosperi.com\/en\/wp-json\/wp\/v2\/product_brand?post=6082"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ornellaprosperi.com\/en\/wp-json\/wp\/v2\/product_cat?post=6082"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ornellaprosperi.com\/en\/wp-json\/wp\/v2\/product_tag?post=6082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}